{"id":4235,"date":"2025-03-14T19:39:08","date_gmt":"2025-03-15T01:39:08","guid":{"rendered":"https:\/\/www.musclenutrition.com.mx\/?post_type=product&#038;p=4235"},"modified":"2026-06-09T11:03:12","modified_gmt":"2026-06-09T17:03:12","slug":"allmax-l-citrulline","status":"publish","type":"product","link":"https:\/\/www.musclenutrition.com.mx\/index.php\/producto\/allmax-l-citrulline\/","title":{"rendered":"ALLMAX L CITRULLINE"},"content":{"rendered":"<p>Suplementos de calidad profesional<\/p>\n<p>El Malato de citrulina [2:1] de Allmax mejora la intensidad del entrenamiento, la resistencia y la velocidad de recuperaci\u00f3n. Lo realiza a trav\u00e9s de 5\u00a0funciones principales:<\/p>\n<p>1) Aumenta los niveles de arginina en la sangre (gramo por gramo al doble del nivel de arginina).<\/p>\n<p>2) Aumenta los niveles de \u00f3xido n\u00edtrico endotelial y, por lo tanto, mejora la funci\u00f3n vascular y el flujo sangu\u00edneo.<\/p>\n<p>3) Mejora la reabsorci\u00f3n de bicarbonato de los ri\u00f1ones y proporciona un potente amortiguador contra el aumento de la acidificaci\u00f3n muscular durante el entrenamiento intenso.<\/p>\n<p>4) Desintoxica el tejido muscular fatigado al eliminar el amon\u00edaco (una toxina que puede multiplicarse por 3 durante el entrenamiento intenso).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suplementos de calidad profesional El Malato de citrulina [2:1] de Allmax mejora la intensidad del entrenamiento, la resistencia y la velocidad de recuperaci\u00f3n. Lo realiza a trav\u00e9s de 5\u00a0funciones principales: 1) Aumenta los niveles de arginina en la sangre (gramo por gramo al doble del nivel de arginina). 2) Aumenta los niveles de \u00f3xido n\u00edtrico &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.musclenutrition.com.mx\/index.php\/producto\/allmax-l-citrulline\/\"> <span class=\"screen-reader-text\">ALLMAX L CITRULLINE<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"featured_media":4239,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"product_brand":[],"product_cat":[33],"product_tag":[],"class_list":{"0":"post-4235","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aminoacidos","7":"desktop-align-left","8":"tablet-align-left","9":"mobile-align-left","11":"first","12":"outofstock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"ams_default_variation_id":0,"ams_product_points_reward":[],"ams_product_discount_percentage":0,"ams_price_to_display":520,"ams_acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline.jpg",500,500,false],"thumbnail":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline-150x150.jpg",150,150,true],"medium":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline-300x300.jpg",300,300,true],"medium_large":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline.jpg",500,500,false],"large":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline.jpg",500,500,false],"1536x1536":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline.jpg",500,500,false],"2048x2048":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline.jpg",500,500,false],"woocommerce_thumbnail":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline.jpg",500,500,false],"woocommerce_gallery_thumbnail":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline-100x100.jpg",100,100,true],"dgwt-wcas-product-suggestion":["https:\/\/www.musclenutrition.com.mx\/wp-content\/uploads\/2025\/03\/all-max-citulline-64x64.jpg",64,64,true]},"uagb_author_info":{"display_name":"ventas reynosa","author_link":"https:\/\/www.musclenutrition.com.mx\/index.php\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Suplementos de calidad profesional El Malato de citrulina [2:1] de Allmax mejora la intensidad del entrenamiento, la resistencia y la velocidad de recuperaci\u00f3n. Lo realiza a trav\u00e9s de 5\u00a0funciones principales: 1) Aumenta los niveles de arginina en la sangre (gramo por gramo al doble del nivel de arginina). 2) Aumenta los niveles de \u00f3xido n\u00edtrico&hellip;","_links":{"self":[{"href":"https:\/\/www.musclenutrition.com.mx\/index.php\/wp-json\/wp\/v2\/product\/4235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.musclenutrition.com.mx\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.musclenutrition.com.mx\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.musclenutrition.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.musclenutrition.com.mx\/index.php\/wp-json\/wp\/v2\/media\/4239"}],"wp:attachment":[{"href":"https:\/\/www.musclenutrition.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4235"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.musclenutrition.com.mx\/index.php\/wp-json\/wp\/v2\/product_brand?post=4235"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.musclenutrition.com.mx\/index.php\/wp-json\/wp\/v2\/product_cat?post=4235"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.musclenutrition.com.mx\/index.php\/wp-json\/wp\/v2\/product_tag?post=4235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}